{"id":6992,"date":"2023-07-28T10:00:00","date_gmt":"2023-07-28T09:00:00","guid":{"rendered":"https:\/\/mexicotransportservice.com\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/"},"modified":"2026-03-26T16:55:53","modified_gmt":"2026-03-26T15:55:53","slug":"como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico","status":"publish","type":"post","link":"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/","title":{"rendered":"Como chegar de San Crist\u00f3bal de las Casas a Bonampak, M\u00e9xico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><span class=\"tadv-color\" style=\"font-weight: bold; color: rgb(5, 22, 77);\">Pode viajar de San Crist\u00f3bal de las Casas para Bonampak de autocarro + excurs\u00e3o, transfer privado ou carro alugado<\/span><span class=\"tadv-color\" style=\"font-weight: bold; color: rgb(5, 22, 77);\">. Consulte o nosso guia com toda a informa\u00e7\u00e3o essencial.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"color:#64748b;font-size:14px\"><em>Verificado por <a href=\"https:\/\/mexicotransportservice.com\/pt-br\/sobre-nos\/\">Jean N\u00e1jera<\/a>, Especialista em Transporte<\/em><\/p>\n\n\n<p class=\"wp-block-paragraph\">Escondido nas profundezas da exuberante e verdejante floresta tropical de Lacandon, no sul do M\u00e9xico, encontra-se um extraordin\u00e1rio tesouro arqueol\u00f3gico chamado Bonampak.<\/p>\n\n<p class=\"wp-block-paragraph\">Este antigo local maia \u00e9 um pa\u00eds das maravilhas da arte e arquitetura maias de cortar a respira\u00e7\u00e3o, oferecendo aos visitantes um vislumbre da vida quotidiana e dos costumes dos antigos maias atrav\u00e9s dos seus murais intrincadamente detalhados. <\/p>\n\n<p class=\"wp-block-paragraph\">Os detalhes intrincados dos murais foram notavelmente preservados, levando-o numa viagem atrav\u00e9s da civiliza\u00e7\u00e3o Maia, fazendo de Bonampak um destino obrigat\u00f3rio para os amantes da hist\u00f3ria e da arte! <\/p>\n\n<p class=\"wp-block-paragraph\">Embarque numa aventura inesquec\u00edvel com a nossa <a href=\"https:\/\/www.getyourguide.com\/palenque-l179804\/palenque-2-day-lacandon-jungle-yaxchilan-bonampak-trip-t432157\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;cmp=MexicoTransport-san-cristobal-de-las-casas-to-bonampak-mexico\" rel=\"nofollow noopener\" target=\"_blank\">viagem de 2 dias \u00e0 Selva Lacandona, Yaxchilan e Bonampak a partir de Palenque<\/a>.  <\/p>\n\n<p class=\"wp-block-paragraph\">Explorar\u00e1 o cora\u00e7\u00e3o da exuberante selva de Lacandon, visitar\u00e1 as cativantes ru\u00ednas antigas de Yaxchilan e testemunhar\u00e1 os frescos de Bonampak, de cortar a respira\u00e7\u00e3o!<\/p>\n\n<p class=\"wp-block-paragraph\">Com um guia experiente a gui\u00e1-lo, aprender\u00e1 sobre a fascinante hist\u00f3ria e cultura da regi\u00e3o e ter\u00e1 a oportunidade de mergulhar na beleza natural da selva.  <\/p>\n\n<p class=\"wp-block-paragraph\">N\u00e3o perca esta viagem extraordin\u00e1ria que o deixar\u00e1 com mem\u00f3rias eternas.  <a href=\"https:\/\/www.getyourguide.com\/palenque-l179804\/palenque-2-day-lacandon-jungle-yaxchilan-bonampak-trip-t432157\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;cmp=MexicoTransport-san-cristobal-de-las-casas-to-bonampak-mexico\" rel=\"nofollow noopener\" target=\"_blank\">Reserve j\u00e1 a sua visita!<\/a><\/p>\n\n<div data-gyg-href=\"https:\/\/widget.getyourguide.com\/default\/availability.frame\" data-gyg-tour-id=\"432157\" data-gyg-locale-code=\"en-US\" data-gyg-currency=\"USD\" data-gyg-widget=\"availability\" data-gyg-theme=\"light\" data-gyg-variant=\"horizontal\" data-gyg-partner-id=\"RJQ408Z\" data-gyg-cmp=\"MexicoTransport-san-cristobal-de-las-casas-to-bonampak-mexico\"><\/div>\n\n<p class=\"wp-block-paragraph\">Consulte o nosso guia para obter todas as informa\u00e7\u00f5es importantes sobre a viagem de <a href=\"https:\/\/shrsl.com\/3v1cu\" rel=\"nofollow noopener\" target=\"_blank\">San Crist\u00f3bal de las Casas a Bonampak.<\/a><\/p>\n\n<div class=\"wp-block-group quick-answer has-background is-layout-constrained wp-container-core-group-is-layout-0d2d72cd wp-block-group-is-layout-constrained\" style=\"border-left-color:#16a34a;border-left-width:4px;background-color:#f0fdf4;padding-top:20px;padding-right:24px;padding-bottom:20px;padding-left:24px\">\n\n<p class=\"wp-block-paragraph\" style=\"font-size:18px;font-style:normal;font-weight:700\">\u26a1 Resposta R\u00e1pida<\/p>\n\n\n<p class=\"wp-block-paragraph\">V\u00e1rias op\u00e7\u00f5es de transporte est\u00e3o dispon\u00edveis de San Crist\u00f3bal de las Casas para Bonampak. Consulte os hor\u00e1rios e pre\u00e7os atuais abaixo para encontrar a melhor op\u00e7\u00e3o para a sua viagem.<\/p>\n\n<\/div>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Distancia_de_San_Cristobal_de_las_Casas_a_Bonampak\" >Dist\u00e2ncia de San Crist\u00f3bal de las Casas a Bonampak<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Opcoes_de_transporte_de_San_Cristobal_de_las_Casas_ate_Bonampak\" >Op\u00e7\u00f5es de transporte de San Crist\u00f3bal de las Casas at\u00e9 Bonampak<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Chegar_a_Bonampak_a_partir_de_San_Cristobal_de_las_Casas\" >Chegar a Bonampak a partir de San Crist\u00f3bal de las Casas<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#1_Autocarro_OCC_excursao_de_San_Cristobal_de_las_Casas_a_Bonampak_via_Palenque\" >1. Autocarro OCC + excurs\u00e3o de San Crist\u00f3bal de las Casas a Bonampak via Palenque<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#San_Cristobal_de_las_Casas_a_Palenque_Programacao_de_autocarros_da_OCC\" >San Crist\u00f3bal de las Casas a Palenque Programa\u00e7\u00e3o de autocarros da OCC<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#2_Transfere_privado_de_San_Cristobal_de_las_Casas_para_Bonampak\" >2. Transfere privado de San Crist\u00f3bal de las Casas para Bonampak<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#3_Conduzir_com_carro_de_aluguer_de_San_Cristobal_de_las_Casas_ate_Bonampak\" >3. Conduzir com carro de aluguer de San Crist\u00f3bal de las Casas at\u00e9 Bonampak<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Melhores_excursoes_de_um_dia_em_Bonampak_Mexico\" >Melhores excurs\u00f5es de um dia em Bonampak, M\u00e9xico<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Perguntas_Mais_Frequentes\" >Perguntas Mais Frequentes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Qual_e_a_opcao_mais_barata_de_San_Cristobal_de_las_Casas_para_Bonampak\" >Qual \u00e9 a op\u00e7\u00e3o mais barata de San Crist\u00f3bal de las Casas para Bonampak?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Qual_e_a_forma_mais_rapida_de_ir_de_San_Cristobal_de_las_Casas_para_Bonampak\" >Qual \u00e9 a forma mais r\u00e1pida de ir de San Crist\u00f3bal de las Casas para Bonampak?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#E_seguro_viajar_para_Bonampak\" >\u00c9 seguro viajar para Bonampak?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Preciso_de_um_guia_para_visitar_Bonampak\" >Preciso de um guia para visitar Bonampak?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#O_que_devo_levar_para_uma_viagem_a_Bonampak\" >O que devo levar para uma viagem a Bonampak?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Ha_alguma_taxa_de_entrada_para_as_Ruinas_de_Bonampak\" >H\u00e1 alguma taxa de entrada para as Ru\u00ednas de Bonampak?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-bonampak-mexico\/#Mais_rotas_a_partir_de_San_Cristobal_de_las_Casas\" >Mais rotas a partir de San Crist\u00f3bal de las Casas<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Distancia_de_San_Cristobal_de_las_Casas_a_Bonampak\"><\/span>Dist\u00e2ncia de San Crist\u00f3bal de las Casas a Bonampak<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">A dist\u00e2ncia de San Crist\u00f3bal de las Casas a Bonampak \u00e9 de cerca de 338 quil\u00f3metros ou 210 milhas.<\/p>\n\n<p class=\"wp-block-paragraph\">Demora cerca de 7,5-8 horas a viajar de carro de San Crist\u00f3bal de las Casas para Bonampak.<\/p>\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m28!1m12!1m3!1d978009.9246336955!2d-92.11038805749052!3d16.759190495399054!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m13!3e6!4m5!1s0x85ed453b1ea89bcf%3A0x48d55ca34957e2de!2sSan%20Cristobal%20de%20las%20Casas%2C%20Chis.%2C%20Mexico!3m2!1d16.7370359!2d-92.6376186!4m5!1s0x85f4afe43bf63773%3A0xf366660b93c91749!2sBonampak%2C%2029933%20Chis.%2C%20Mexico!3m2!1d16.703927!2d-91.0646409!5e0!3m2!1sen!2smk!4v1680082479333!5m2!1sen!2smk\" width=\"100%\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n<div class=\"wp-block-group info-box-block is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group info-box-block is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"transportation-options-from-cancun-to-tulum\"><span class=\"ez-toc-section\" id=\"Opcoes_de_transporte_de_San_Cristobal_de_las_Casas_ate_Bonampak\"><\/span>Op\u00e7\u00f5es de transporte de San Crist\u00f3bal de las Casas at\u00e9 Bonampak<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A tabela seguinte descreve <a href=\"https:\/\/shrsl.com\/3v1cu\" rel=\"nofollow noopener\" target=\"_blank\">todas as op\u00e7\u00f5es de transporte de San Crist\u00f3bal de las Casas at\u00e9 Bonampak<\/a>:<\/em><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th><strong>M\u00e9todo<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>Tempo de viagem<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>Pre\u00e7o<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Autocarro OCC + excurs\u00e3o de San Crist\u00f3bal de las Casas a Bonampak via Palenque<\/td><td class=\"has-text-align-center\" data-align=\"center\">&#8211;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&#8211;<\/td><\/tr><tr><td><a href=\"https:\/\/shrsl.com\/3v1cu\" rel=\"nofollow noopener\" target=\"_blank\">Transfere privado de San Crist\u00f3bal de las Casas para Bonampak<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\">~8 horas<\/td><td class=\"has-text-align-center\" data-align=\"center\">USD 359-USD 599<\/td><\/tr><tr><td>Aluguer de Autom\u00f3veis de San Crist\u00f3bal de las Casas para Bonampak<\/td><td class=\"has-text-align-center\" data-align=\"center\">7,5 horas<\/td><td class=\"has-text-align-center\" data-align=\"center\">&#8211;<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading has-text-align-center\"><span class=\"ez-toc-section\" id=\"Chegar_a_Bonampak_a_partir_de_San_Cristobal_de_las_Casas\"><\/span><strong>Chegar a Bonampak a partir de San Crist\u00f3bal de las Casas<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<div class=\"searchbar\"><iframe loading=\"lazy\" style=\"overflow-x: hidden; border: none; border-radius: 12px;\" src=\"https:\/\/shrsl.com\/3shtt%09%0A\" width=\"100%\" height=\"540\"><\/iframe><\/div>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Autocarro_OCC_excursao_de_San_Cristobal_de_las_Casas_a_Bonampak_via_Palenque\"><\/span>1. Autocarro OCC + excurs\u00e3o de San Crist\u00f3bal de las Casas a Bonampak via Palenque<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\"><em><strong><strong>Dura\u00e7\u00e3o da viagem<\/strong>: 2 dias<\/strong> <\/em><\/p>\n\n<p class=\"wp-block-paragraph\">Como o transporte direto de San Cristobal de Las Casas para Bonampak \u00e9 bastante limitado, a primeira alternativa \u00e9 apanhar um autocarro para Palenque e fazer uma visita guiada a Bonampak.<\/p>\n\n<p class=\"wp-block-paragraph\">Em primeiro lugar, apanhar um autocarro de San Crist\u00f3bal de las Casas para Palenque.<\/p>\n\n<p class=\"wp-block-paragraph\">Os autocarros da OCC efectuam servi\u00e7os di\u00e1rios de San Crist\u00f3bal de las Casas para Palenque por apenas 31 USD!<\/p>\n\n<p class=\"wp-block-paragraph\">A viagem dura normalmente cerca de 9 horas. No entanto, os autocarros s\u00e3o confort\u00e1veis, climatizados e equipados com assentos reclin\u00e1veis, o que torna a viagem agrad\u00e1vel atrav\u00e9s das paisagens c\u00e9nicas de Chiapas. <\/p>\n\n<p class=\"wp-block-paragraph\">Recomendamos que <a href=\"https:\/\/shrsl.com\/3v1cb\" rel=\"nofollow noopener\" target=\"_blank\">reserve os seus bilhetes de autocarro com anteced\u00eancia<\/a>, seja online ou na esta\u00e7\u00e3o de autocarros, uma vez que os lugares podem esgotar rapidamente durante as \u00e9pocas altas.<\/p>\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"San_Cristobal_de_las_Casas_a_Palenque_Programacao_de_autocarros_da_OCC\"><\/span>San Crist\u00f3bal de las Casas a Palenque Programa\u00e7\u00e3o de autocarros da OCC<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Hora de sa\u00edda<\/th><th class=\"has-text-align-center\" data-align=\"center\">Hora de Chegada<\/th><th class=\"has-text-align-center\" data-align=\"center\">Dura\u00e7\u00e3o<\/th><th class=\"has-text-align-center\" data-align=\"center\">Pre\u00e7o por pessoa<\/th><th><\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">12:00 PM<\/td><td class=\"has-text-align-center\" data-align=\"center\">21:15 PM<\/td><td class=\"has-text-align-center\" data-align=\"center\">9 horas 15 minutos<\/td><td class=\"has-text-align-center\" data-align=\"center\">31 USD<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">22:00 PM<\/td><td class=\"has-text-align-center\" data-align=\"center\">07:20 AM<\/td><td class=\"has-text-align-center\" data-align=\"center\">9 horas 20 minutos<\/td><td class=\"has-text-align-center\" data-align=\"center\">31 USD<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/shrsl.com\/3v1cb\" rel=\"nofollow noopener\" target=\"_blank\">Clique aqui para reservar um bilhete de autocarro OCC de San Crist\u00f3bal de las Casas para Palenque!<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Dado o tempo de viagem entre San Crist\u00f3bal e Palenque, recomenda-se passar uma noite em Palenque antes de embarcar na visita guiada a Bonampak.  <\/p>\n\n<p class=\"wp-block-paragraph\">Isto permitir-lhe-\u00e1 descansar, recarregar baterias e, eventualmente, explorar o s\u00edtio arqueol\u00f3gico de Palenque, outra fascinante ru\u00edna Maia.<\/p>\n\n<p class=\"wp-block-paragraph\">De Palenque, pode <a href=\"https:\/\/www.getyourguide.com\/palenque-l179804\/palenque-2-day-lacandon-jungle-yaxchilan-bonampak-trip-t432157\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;cmp=MexicoTransport-san-cristobal-de-las-casas-to-bonampak-mexico\" rel=\"nofollow noopener\" target=\"_blank\">reservar uma visita guiada a Bonampak<\/a>, que tamb\u00e9m o levar\u00e1 atrav\u00e9s da Selva Lacandona e de Yaxchilan!<\/p>\n\n<p class=\"wp-block-paragraph\">Estas excurs\u00f5es incluem normalmente transporte de e para Bonampak, taxas de entrada e um guia especializado que pode fornecer informa\u00e7\u00f5es fascinantes sobre a hist\u00f3ria, cultura e arquitetura da civiliza\u00e7\u00e3o Maia.  <\/p>\n\n<p class=\"wp-block-paragraph\">A viagem de Palenque a Bonampak demora cerca de 2,5 horas, passando por paisagens de selva exuberante e comunidades rurais, e a excurs\u00e3o completa dura dois dias.<\/p>\n\n<p class=\"wp-block-paragraph\">As excurs\u00f5es s\u00e3o uma escolha popular para os viajantes que querem visitar Bonampak e s\u00e3o uma forma conveniente e informativa de conhecer a rica hist\u00f3ria e a beleza impressionante deste antigo s\u00edtio maia!<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.getyourguide.com\/palenque-l179804\/palenque-2-day-lacandon-jungle-yaxchilan-bonampak-trip-t432157\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;cmp=MexicoTransport-san-cristobal-de-las-casas-to-bonampak-mexico\" rel=\"nofollow noopener\" target=\"_blank\">Veja todos os detalhes e reserve j\u00e1 esta excurs\u00e3o a Bonampak!<\/a><\/p>\n\n<div data-gyg-href=\"https:\/\/widget.getyourguide.com\/default\/availability.frame\" data-gyg-tour-id=\"432157\" data-gyg-locale-code=\"en-US\" data-gyg-currency=\"USD\" data-gyg-widget=\"availability\" data-gyg-theme=\"light\" data-gyg-variant=\"horizontal\" data-gyg-partner-id=\"RJQ408Z\" data-gyg-cmp=\"MexicoTransport-san-cristobal-de-las-casas-to-bonampak-mexico\"><\/div>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-2-1024x684.jpg\" alt=\"\" class=\"wp-image-5406\" title=\"\" srcset=\"https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-2-1024x684.jpg 1024w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-2-300x200.jpg 300w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-2-768x513.jpg 768w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-2-960x641.jpg 960w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-2-1080x721.jpg 1080w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-2.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Transfere_privado_de_San_Cristobal_de_las_Casas_para_Bonampak\"><\/span>2. Transfere privado de San Crist\u00f3bal de las Casas para Bonampak<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\"><strong><em><em><strong><em><strong><strong>Tempo de viagem<\/strong>: ~8 horas<\/strong><\/em><\/strong><\/em><\/em><\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Ao viajar de San Crist\u00f3bal de las Casas para Bonampak, a conveni\u00eancia e o conforto de <a href=\"https:\/\/shrsl.com\/3v1cu\" rel=\"nofollow noopener\" target=\"_blank\">um transfer privado<\/a> podem fazer toda a diferen\u00e7a.  <\/p>\n\n<p class=\"wp-block-paragraph\">Com esta op\u00e7\u00e3o, ter\u00e1 liberdade para viajar ao seu pr\u00f3prio ritmo e parar para apreciar a paisagem deslumbrante.  <\/p>\n\n<p class=\"wp-block-paragraph\">O seu motorista ser\u00e1 experiente e conhecedor, capaz de lhe fornecer informa\u00e7\u00f5es valiosas sobre a cultura e a hist\u00f3ria locais. <\/p>\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, n\u00e3o ter\u00e1 de se preocupar com a navega\u00e7\u00e3o em estradas desconhecidas. Em vez disso, pode sentar-se, relaxar e desfrutar da viagem at\u00e9 Bonampak com conforto e estilo.<\/p>\n\n<p class=\"wp-block-paragraph\">Pode definir o seu itiner\u00e1rio e chegar a Bonampak em cerca de 8 horas!<\/p>\n\n<p class=\"wp-block-paragraph\">Esta \u00e9 uma excelente escolha para grupos que viajam juntos, uma vez que o pre\u00e7o compensa quando \u00e9 dividido entre os passageiros.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/shrsl.com\/3v1cu\" rel=\"nofollow noopener\" target=\"_blank\">Por isso, veja todas as op\u00e7\u00f5es de transferes privados e reserve aqui a sua viagem de San Cristobal de Las Casas para Bonampak!<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/shrsl.com\/3v1cu\" rel=\"nofollow noopener\" target=\"_blank\">Pre\u00e7os para um transfer privado de San Crist\u00f3bal de las Casas para Bonampak<\/a><\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>1-3 Passageiros: 359 USD<\/li>\n\n\n\n<li>4-6 Passageiros: 594 USD<\/li>\n\n\n\n<li>7-9 Passageiros: 599 USD<\/li>\n<\/ul>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/shrsl.com\/3v1cu\" rel=\"nofollow noopener\" target=\"_blank\">Clique aqui para efetuar uma reserva de um transfer privado de San Crist\u00f3bal de las Casas para Bonampak!<\/a><\/div>\n<\/div>\n<div class=\"searchbar\"><iframe loading=\"lazy\" style=\"overflow-x: hidden; border: none; border-radius: 12px;\" src=\"https:\/\/shrsl.com\/3shtt\t\n\" width=\"100%\" height=\"540\"><\/iframe><\/div>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-1-1024x683.jpg\" alt=\"\" class=\"wp-image-5399\" title=\"\" srcset=\"https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-1-1024x683.jpg 1024w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-1-300x200.jpg 300w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-1-768x512.jpg 768w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-1-960x640.jpg 960w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-1-1080x720.jpg 1080w, https:\/\/mexicotransportservice.com\/wp-content\/uploads\/2022\/12\/San-Cristobal-de-las-Casas-to-Bonampak-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Conduzir_com_carro_de_aluguer_de_San_Cristobal_de_las_Casas_ate_Bonampak\"><\/span>3. Conduzir com carro de aluguer de San Crist\u00f3bal de las Casas at\u00e9 Bonampak<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\"><em><strong><strong>Tempo de viagem<\/strong>: 7,5 horas<\/strong><\/em><\/p>\n\n<p class=\"wp-block-paragraph\">Se quiser ter mais controlo sobre o seu hor\u00e1rio de viagem, <a href=\"https:\/\/www.rentalcars.com\/?affiliateCode=universal430&amp;adcamp=mexicotransportservice-san-cristobal-de-las-casas-to-bonampak-mexico\" rel=\"nofollow noopener\" target=\"_blank\">alugar um carro<\/a> \u00e9 uma excelente op\u00e7\u00e3o para a sua viagem de San Cristobal de las Casas a Bonampak.  <\/p>\n\n<p class=\"wp-block-paragraph\">Permite-lhe definir o seu pr\u00f3prio ritmo e explorar os pontos tur\u00edsticos. Al\u00e9m disso, pode chegar a Boanmpak mais rapidamente, uma vez que a viagem demora cerca de 7 horas e 30 minutos!<\/p>\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, com um carro, n\u00e3o ter\u00e1 de se preocupar em cumprir o hor\u00e1rio de outra pessoa ou em pagar um transporte individual. <\/p>\n\n<p class=\"wp-block-paragraph\">No entanto, \u00e9 importante notar que a estrada para Bonampak pode ser um desafio devido ao seu terreno estreito e n\u00e3o pavimentado, por isso certifique-se de que tem um carro fi\u00e1vel e adequado para a viagem.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.rentalcars.com\/?affiliateCode=universal430&amp;adcamp=mexicotransportservice-san-cristobal-de-las-casas-to-bonampak-mexico\" data-type=\"page\" rel=\"nofollow noopener\" target=\"_blank\">Recomendamos que consulte todas as op\u00e7\u00f5es com anteced\u00eancia e fa\u00e7a a sua reserva aqui!<\/a><\/p>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading has-text-align-center\"><span class=\"ez-toc-section\" id=\"Melhores_excursoes_de_um_dia_em_Bonampak_Mexico\"><\/span>Melhores excurs\u00f5es de um dia em Bonampak, M\u00e9xico<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.getyourguide.com\/palenque-l179804\/palenque-2-day-lacandon-jungle-yaxchilan-bonampak-trip-t432157\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;cmp=MexicoTransport-san-cristobal-de-las-casas-to-bonampak-mexico\" rel=\"nofollow noopener\" target=\"_blank\">Obtenha o seu Guia<\/a> \u00e9 a sua melhor escolha para todos os seus planos de viagem! Ajudaram sempre a tornar as minhas viagens excitantes e inesquec\u00edveis, por isso recomendo-os vivamente!<\/p>\n\n<p class=\"wp-block-paragraph\">Com Get Your Guide, pode descobrir aut\u00eanticas aventuras de viagem e tirar partido de sugest\u00f5es e itiner\u00e1rios personalizados com mais de 60.000 visitas guiadas, pontos de refer\u00eancia famosos e muito mais!<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Veja os seguintes widgets para mais <a href=\"https:\/\/www.getyourguide.com\/palenque-l179804\/palenque-2-day-lacandon-jungle-yaxchilan-bonampak-trip-t432157\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;cmp=MexicoTransport-san-cristobal-de-las-casas-to-bonampak-mexico\" rel=\"nofollow noopener\" target=\"_blank\">excurs\u00f5es de um dia em Bonampak, M\u00e9xico!<\/a><\/em><\/p>\n\n<div data-gyg-href=\"https:\/\/widget.getyourguide.com\/default\/activities.frame\" data-gyg-locale-code=\"en-US\" data-gyg-widget=\"activities\" data-gyg-number-of-items=\"3\" data-gyg-cmp=\"MexicoTransportService\" data-gyg-partner-id=\"RJQ408Z\" data-gyg-q=\"mexico\"><\/div>\n\n<h2 class=\"wp-block-heading has-text-align-center\"><span class=\"ez-toc-section\" id=\"Perguntas_Mais_Frequentes\"><\/span>Perguntas Mais Frequentes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<div class=\"searchbar\"><iframe loading=\"lazy\" style=\"overflow-x: hidden; border: none; border-radius: 12px;\" src=\"https:\/\/shrsl.com\/3shtt%09%0A\" width=\"100%\" height=\"540\"><\/iframe><\/div>\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1667807706183\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Qual_e_a_opcao_mais_barata_de_San_Cristobal_de_las_Casas_para_Bonampak\"><\/span>Qual \u00e9 a op\u00e7\u00e3o mais barata de San Crist\u00f3bal de las Casas para Bonampak?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>A op\u00e7\u00e3o mais barata de San Crist\u00f3bal de las Casas para Bonampak \u00e9 de carro alugado. Dependendo do tipo de carro e da empresa de aluguer, esta op\u00e7\u00e3o compensa para alguns dias de viagem, especialmente se estiver com um grupo.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1667807714110\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Qual_e_a_forma_mais_rapida_de_ir_de_San_Cristobal_de_las_Casas_para_Bonampak\"><\/span>Qual \u00e9 a forma mais r\u00e1pida de ir de San Crist\u00f3bal de las Casas para Bonampak?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>A forma mais r\u00e1pida de ir de San Crist\u00f3bal de las Casas a Bonampak \u00e9 de carro. A dura\u00e7\u00e3o da viagem de San Crist\u00f3bal de las Casas a Bonampak \u00e9 de cerca de 7,5 a 8 horas.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1680084637314\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"E_seguro_viajar_para_Bonampak\"><\/span>\u00c9 seguro viajar para Bonampak?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Bonampak \u00e9 geralmente considerado seguro para os turistas, mas \u00e9 sempre uma boa ideia tomar as precau\u00e7\u00f5es necess\u00e1rias e pesquisar os riscos potenciais antes de viajar.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1680084652198\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Preciso_de_um_guia_para_visitar_Bonampak\"><\/span>Preciso de um guia para visitar Bonampak?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Embora n\u00e3o seja obrigat\u00f3rio, ter um guia pode melhorar a sua experi\u00eancia e fornecer informa\u00e7\u00f5es valiosas sobre a hist\u00f3ria e o significado do local.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1680084668833\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"O_que_devo_levar_para_uma_viagem_a_Bonampak\"><\/span>O que devo levar para uma viagem a Bonampak?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Recomenda-se que traga roupa e cal\u00e7ado confort\u00e1veis, protetor solar, repelente de insectos e muita \u00e1gua. Se planeia passar a noite, n\u00e3o se esque\u00e7a de trazer os artigos de higiene pessoal necess\u00e1rios e os artigos essenciais para a noite.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1680084836975\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Ha_alguma_taxa_de_entrada_para_as_Ruinas_de_Bonampak\"><\/span>H\u00e1 alguma taxa de entrada para as Ru\u00ednas de Bonampak?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Sim, h\u00e1 uma taxa de entrada de MXN 55, ou cerca de USD 3 para visitar as Ru\u00ednas de Bonampak.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wp-block-group box is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\"><span class=\"ez-toc-section\" id=\"Mais_rotas_a_partir_de_San_Cristobal_de_las_Casas\"><\/span>Mais rotas a partir de San Crist\u00f3bal de las Casas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-palenque-mexico\/\" data-type=\"post\" data-id=\"6155\">San Crist\u00f3bal de las Casas a Palenque<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-ir-de-san-cristobal-de-las-casas-para-misol-ha-mexico\/\" data-type=\"post\" data-id=\"6159\">San Crist\u00f3bal de las Casas a Misol-Ha<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-ir-de-san-cristobal-de-las-casas-para-as-ruinas-de-palenque-mexico\/\" data-type=\"post\" data-id=\"6157\">San Crist\u00f3bal de las Casas \u00e0s Ru\u00ednas de Palenque<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/mexicotransportservice.com\/pt-br\/como-chegar-de-san-cristobal-de-las-casas-a-cachoeira-da-agua-azul-mexico\/\" data-type=\"post\" data-id=\"6161\">San Crist\u00f3bal de las Casas para Agua Azul<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;6992&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 voto)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Como chegar de San Crist\u00f3bal de las Casas a Bonampak, M\u00e9xico&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pode viajar de San Crist\u00f3bal de las Casas para Bonampak de autocarro + excurs\u00e3o, transfer privado ou carro alugado. Consulte&#8230;<\/p>\n","protected":false},"author":3,"featured_media":5404,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-6992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rutas-de-mexico"],"_links":{"self":[{"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/posts\/6992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/comments?post=6992"}],"version-history":[{"count":4,"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/posts\/6992\/revisions"}],"predecessor-version":[{"id":12567,"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/posts\/6992\/revisions\/12567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/media\/5404"}],"wp:attachment":[{"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/media?parent=6992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/categories?post=6992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mexicotransportservice.com\/pt-br\/wp-json\/wp\/v2\/tags?post=6992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}